{"id":250196,"date":"2023-05-30T12:57:20","date_gmt":"2023-05-30T10:57:20","guid":{"rendered":"https:\/\/coaching-your-change.com\/?p=250196"},"modified":"2023-10-11T09:14:58","modified_gmt":"2023-10-11T07:14:58","slug":"ursachen-misserfolg-transformationen","status":"publish","type":"post","link":"https:\/\/coaching-your-change.com\/en_gb\/ursachen-misserfolg-transformationen\/","title":{"rendered":"6 Reasons for the failure of transformations"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Failure in numbers<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">One thing is obvious: we must learn to transform both better and faster!<br>70% aller Ver\u00e4nderungsprogramme erreichen nicht das gew\u00fcnschte Ziel &#8211; immer noch! Egal ob wir Deloitte, Bain &amp; Company, KPMG, BCG oder Capgemini fragen, diese Zahl erscheint seit Jahren immer wieder in den Umfragen. Doch was sind die Ursachen f\u00fcr den Misserfolg von Transformationen? Allein im Jahr 2022 gingen dadurch in der digitalen Transformation 900 Billionen US-Dollar verloren (Forbes Technology Council). Werden wir denn gar nicht besser? Nein, es scheint, wir werden schlechter! <a href=\"https:\/\/www.porsche-consulting.com\/de\/medien\/publikationen\/detail\/strategy-paper-strategic-change-management\/\" target=\"_blank\" rel=\"noreferrer noopener\">Porsche Consulting<\/a> shows in its latest study that only 20% of German companies achieve their strategic transformation goals. In the areas of transport, mobility &amp; logistics, in the public sector &amp; infrastructure and in the technology &amp; telecommunications industry, the success rate is a maximum of 15%. In the case of digital transformations, as many as 94% fail to achieve their goal! Why is that?<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">In the public sector, the set of rules to be observed is enormously demanding, and comprehensive and holistic reforms take years. In addition, there is hardly any other sector with so little scope within established framework conditions. Legal consequences must always be expected. Where is the source of energy for engagement, the scope for empowerment and agile ways of working?<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">In the technology and telecommunications industry, it is due to the incredible speed with which new things are developed and old things become obsolete. The adaptation cycles take too long. If we bet on a horse that is modern today, it is already old hat by the time it is implemented. The bigger the company, the more comprehensive the adaptation programmes. But time is now the decisive factor! Start-ups are conquering the market with new ideas, are small, light and agile and have designed their business model to adapt from the very beginning. The market is in enormous flux. It is no longer about implementing THE transformation programme. It is about living a whole new culture of perpetual adaptation. So we need to get to the bottom of why transformations fail!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img decoding=\"async\" src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-7.png\" alt=\"Tastatur, Brille und Stift auf Business Reports.\" class=\"wp-image-250197\" style=\"width:823px;height:412px\" width=\"823\" height=\"412\" srcset=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-7.png 823w, https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-7-480x240.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 823px, 100vw\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">6 Reasons for the failure of transformations<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">No matter what industry you are in, there are a few factors that can shake up any transformation, no matter how well-intentioned it may be. You should pay attention to these 6 causes in order to recognise and remedy weak points in time:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"has-medium-font-size\"><strong>Lack of vision clarity <\/strong><br>If companies cannot explain exactly why a change is necessary and what they want to achieve with the transformation, it is almost impossible to successfully shape the transformation process or even to activate others for it. What is needed here is not a short-term profit motive, but a vision that people want to follow, even if it means effort. Those who do not know the intended impact through transformation cannot engage effectively. Those who cannot judge whether the desired goal is worthwhile will hold back themselves and their commitment.<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Insufficient leadership support<\/strong><br>One of the main causes of failure in transformation programmes is a lack of commitment and support from leadership. If leaders do not actively model change, set clear goals and demonstrate unity, direction is lacking and the initiative stalls. Competing goals and priorities are poison for any transformation process and a slowdown that most companies cannot afford. In addition, competing goals lead to a lack of resources allocated to the transformation. A tight budget, insufficient staff or an unrealistic timetable will cost credibility and slow down the transformation and probably not bring it to the desired goal.<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Lack of adaptability<\/strong><br>Digital transformation requires agility and the ability to adapt quickly to changing circumstances. If companies are too rigid, have inflexible processes or find it difficult to respond to new demands, this can affect the success of the transformation. Every company is well advised to review the balance between regulations and freedom. What absolutely has to be regulated? What can be decided situationally and depending on the use case by the operational level? When it comes to transforming faster, control clearly loses out to trust in the problem-solving competence of the workforce! Adaptability needs competent complicity!<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Lack of competencies<\/strong><br>Transformation is about strategically realigning together, checking the business model for resilience and acquiring new skills as a company! Which skills are needed in the long term and therefore also valued? How can these skills be acquired? Will the skills training happen within the company or \"are they kicking me out to hire someone who already has those skills?\" Does the planning for transformation take into account time to learn or do employees find themselves being overwhelmed? Depending on how companies deal with this question, they will release hope in the future or strengthen the old.<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Cultural resistance<\/strong><br>Transformations, whether digital or not, often require a profound cultural change within the company. It is not just about accepting new technologies or adapting ways of working. That is too short-sighted and too operational! Transformations essentially change HOW the company's purpose is fulfilled. What will we stand for in the future? What behaviour will promote success and bring us to the goal? How do we deal with old routines? The \"reflexes\" of employees and managers are still completely old school. Developing a new corporate culture through new behaviour is a marathon, not a sprint. It takes a general awareness of the desired behaviours and why they are beneficial for each individual. AND it takes consistent, social reactions to undesirable behaviour. Especially under pressure, we react unconsciously, and usually based on old patterns of success. Culture change is therefore an intensive and exhausting process, with many constructive feedback and correction loops for all involved.<\/li>\n\n\n\n<li class=\"has-medium-font-size\"><strong>Insufficient integration<\/strong><br>Employee involvement is a crucial success factor for transformations. If employees are not actively involved in the transformation process, if their perspectives are not heard, this can lead to frustration and lack of acceptance. Why should it be any other way? People are not lemmings! And people do not like to be the victim of other people's decisions. We cannot shortcut the process of dealing with innovations, forming an opinion and seeking our own way in it. We only lose time if we only involve the staff at the implementation stage. By losing time like this, we risk the failure of our transformation!<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"550\" src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-8.png\" alt=\"\" class=\"wp-image-250200\" srcset=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-8.png 800w, https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-8-480x330.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Bad transformation programmes harm the company<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Over the last few years, we have seen one change programme take over from the next before the first could even produce results. And what have we achieved as a result? That's right - frustration among the staff. The daily work was burdened with additional work - without any real, consequent relief and without the promised results, because we never reached the end, the proposed future scenario. What remains is disillusionment, a tarnished trust in the management team and a declining commitment to the company's goals in general. \u201cAll I want is to just do my job and bring home my salary - anything else I\u2019ll do in my free-time!\" This is exactly what a failure in transformation feels and sounds like.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"800\" height=\"340\" src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/2-11-e1685443940815.png\" alt=\"Wegweiser: Habits und Changes\" class=\"wp-image-250201\" srcset=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/2-11-e1685443940815.png 800w, https:\/\/coaching-your-change.com\/wp-content\/uploads\/2-11-e1685443940815-480x270.png 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 800px, 100vw\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Companies urgently need more change competence<\/h2>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">Aus den Ursachen des Misserfolg von Transformationen zu lernen, ist ein erster Schritt. Doch das wird nicht reichen, um in Zukunft besser und schneller zu werden. Was wir in allen Branchen brauchen, ist eine neue Einstellung zur Ver\u00e4nderung!<br>Every successful transformation requires a change management strategy that ensures acceptance of the desired changes through communication, participation and implementation support. And this strategy is needed at the company level from the first hour of the transformation. It needs change enthusiasts who are curious, ask questions, explore possibilities - without diminishing the value of what has been achieved so far. We need people who can create a spirit of optimism, exude confidence and encourage others to \u201cnew thinking\". And we need significantly increased change competence at all management levels to support precisely these stimulators of change and direct them towards an aligned goal. Companies of the future that can adapt quickly are learning-oriented. They create a culture of development where employees expand their knowledge, learn from mistakes, develop new skills and share best practices. This, together with empowerment and permission to make their own decisions, makes companies faster and more adaptable.<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph\">So that you can find out how high the chances of success for the transformation in your company are, I have put together this short questionnaire. You can use it to check whether there are any weaknesses in your company that make a failure of the transformation likely!<\/p>\n\n\n\n<p class=\"has-medium-font-size wp-block-paragraph translation-block\"><a href=\"https:\/\/coaching-your-change.com\/en_gb\/vulnerability-finder-for-transformations\/\">Click here for your Vulnerability-Finder!<\/a><br><\/p>","protected":false},"excerpt":{"rendered":"<p>Misserfolge in Zahlen Eines ist offensichtlich: Wir m\u00fcssen lernen, besser und schneller zu transformieren!70% aller Ver\u00e4nderungsprogramme erreichen nicht das gew\u00fcnschte Ziel &#8211; immer noch! Egal ob wir Deloitte, Bain &amp; Company, KPMG, BCG oder Capgemini fragen, diese Zahl erscheint seit Jahren immer wieder in den Umfragen. Doch was sind die Ursachen f\u00fcr den Misserfolg von [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":250215,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Misserfolge in Zahlen<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Eines ist offensichtlich: Wir m\u00fcssen lernen, besser und schneller zu transformieren!<br>70% aller Ver\u00e4nderungsprogramme erreichen nicht das gew\u00fcnschte Ziel - immer noch! Egal ob wir Deloitte, Bain &amp; Company, KPMG, BCG oder Capgemini fragen, diese Zahl erscheint seit Jahren immer wieder in den Umfragen. Doch was sind die Ursachen f\u00fcr den Misserfolg von Transformationen? Allein im Jahr 2022 gingen dadurch in der digitalen Transformation 900 Billionen US-Dollar verloren (HBR Research, M\u00e4rz 2018). Werden wir denn gar nicht besser? Nein, es scheint, wir werden schlechter! <a href=\"https:\/\/www.porsche-consulting.com\/de\/medien\/publikationen\/detail\/strategy-paper-strategic-change-management\/\" target=\"_blank\" rel=\"noreferrer noopener\">Porsche Consulting<\/a> weist in ihrer j\u00fcngsten Studie aus, dass nur noch 20% der deutschen Firmen ihre strategischen Transformationsziele erreichen. In den Bereichen Transport, Mobilit\u00e4t &amp; Logistik, im \u00f6ffentlichen Sector &amp; der Infrastruktur und in der Technologie- &amp; Telekommunikationsbranche liegt die Erfolgsquote bei maximal 15%. Bei digitalen Transformationen verfehlen sogar 94% ihr Ziel! Warum ist das so?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Im \u00f6ffentlichen Sektor ist das einzuhaltende Regelwerk enorm anspruchsvoll, umf\u00e4ngliche und ganzheitliche Reformen brauchen Jahre. Zudem ist im kaum einem anderen Sektor so wenig Spielraum innerhalb begr\u00fcndeter Rahmenbedingungen gegeben. Immer ist mit Rechtsfolgen zu rechnen. Wo ist hier die Energiequelle f\u00fcr Engagement, der Spielraum f\u00fcr Empowerment und agile Arbeitsweisen?<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">In der Technologie und Telekommunikationsbranche liegt es an der unglaublichen Geschwindigkeit, mit der Neues entwickelt wird, Altes dementsprechend obsolet. Die Anpassungszyklen dauern zu lang. Setzen wir auf ein heute modernes Pferd, ist es zum Zeitpunkt der Implementierung schon ein alter Hut. Je gr\u00f6\u00dfer das Unternehmen, desto umfassender die Anpassungsprogramme. Doch Zeit ist mittlerweile der entscheidende Faktor! Startups erobern mit neuen Ideen den Markt, sind klein, leicht und agil und haben ihr Business Modell von Anfang an auf Anpassungen ausgelegt. Der Markt ist enorm in Bewegung. Hier geht es nicht mehr darum, DAS Transformationsprogramm umzusetzen. Hier geht es darum, eine ganz neue Kultur der fortw\u00e4hrenden Anpassung zu leben. Wir m\u00fcssen also den Ursachen f\u00fcr den Misserfolg von Transformationen auf den Grund gehen!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":250197,\"width\":823,\"height\":412,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full is-resized\"><img src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-7.png\" alt=\"Tastatur, Brille und Stift auf Business Reports.\" class=\"wp-image-250197\" width=\"823\" height=\"412\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">6 Ursachen f\u00fcr den Misserfolg von Transformationen<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Egal in welcher Branche Du unterwegs bist: Es gibt ein paar Faktoren, die jede noch so gut gewollte Transformation ins Wanken bringen. Auf diese auf 6 Ursachen solltest Du achten, um Schwachstellen rechtzeitig zu erkennen und zu beheben:<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:list -->\n<ul><!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Mangelnde Klarheit der Vision <\/strong><br>Wenn Unternehmen nicht genau erkl\u00e4ren k\u00f6nnen, warum eine Ver\u00e4nderung n\u00f6tig ist und was sie mit der Transformation erreichen wollen, ist es nahezu unm\u00f6glich, den Transformationsprozess erfolgreich zu gestalten oder gar andere daf\u00fcr zu aktivieren. Hier ist kein kurzfristiges Gewinnstreben gefragt, sondern eine Vision, der Menschen folgen wollen, auch wenn es Anstrengung bedeutet. Wer die beabsichtigte Wirkung durch die Transformation nicht kennt, kann sich nicht wirksam einbringen. Wer nicht beurteilen kann, ob sich das angestrebte Ziel lohnt, wird sich und sein Engagement zur\u00fcckhalten.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Unzureichende F\u00fchrungsunterst\u00fctzung<\/strong><br>Eine der Hauptursachen f\u00fcr das Scheitern von Transformationsprogrammen ist ein Mangel an Engagement und Unterst\u00fctzung seitens der F\u00fchrungsebene. Wenn F\u00fchrungskr\u00e4fte nicht aktiv den Wandel vorleben, klare Ziele setzen und Einigkeit demonstrieren, fehlt es an Richtung und die Initiative ger\u00e4t ins Stocken. Konkurrierende Ziele und Priorit\u00e4ten sind Gift f\u00fcr jeden Transformationsprozess und eine Verlangsamung, die sich die meisten Unternehmen nicht leisten k\u00f6nnen. Zudem f\u00fchren konkurrierende Ziele zu einem Mangel an Ressourcen, die der Transformation zur Verf\u00fcgung gestellt werden. Ein knappes Budget, unzureichendes Personal oder ein unrealistischer Zeitplan werden Glaubw\u00fcrdigkeit kosten und den Wandel verlangsamen und vermutlich nicht zum gew\u00fcnschten Ziel bringen.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Fehlende Anpassungsf\u00e4higkeit<\/strong><br>Digitale Transformation erfordert Agilit\u00e4t und die F\u00e4higkeit, sich schnell an ver\u00e4nderte Umst\u00e4nde anzupassen. Wenn Unternehmen zu starr sind, starre Prozesse haben oder Schwierigkeiten haben, auf neue Anforderungen zu reagieren, kann dies den Erfolg der Transformation beeintr\u00e4chtigen. Jedes Unternehmen ist gut beraten, die Balance zwischen Vorgaben und Freiraum zu \u00fcberpr\u00fcfen. Was muss unbedingt geregelt werden? Was kann situativ und je nach Anwendungsfall von der operativen Ebene entschieden werden? Wenn es darum geht, schneller zu transformieren, verliert die Kontrolle ganz klar gegen das Vertrauen in die L\u00f6sungskompetenz der Belegschaft! Anpassungsf\u00e4higkeit braucht kompetente Mitt\u00e4terschaft!<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Fehlende Kompetenzen<\/strong><br>Bei einer Transformation geht es darum, sich gemeinsam strategisch neu auszurichten, das Business Modell auf seine Resilienz hin zu \u00fcberpr\u00fcfen und als Unternehmen neue F\u00e4higkeiten zu erwerben! Welche F\u00e4higkeiten werden langfristig ben\u00f6tigt und daher auch wertgesch\u00e4tzt? Wie k\u00f6nnen diese F\u00e4higkeiten erlangt werden? Wird die Kompetenzerweiterung innerhalb des Unternehmens stattfinden oder \u201eWirft man mich raus, um jemanden einzustellen, der diese F\u00e4higkeiten schon mitbringt?\u201c Ber\u00fccksichtigt die Planung der Transformation Zeit zum Lernen oder finden sich die Mitarbeitenden in der \u00dcberforderung wieder? Je nachdem, wie Unternehmen mit dieser Frage umgehen, werden sie Hoffnung in die Zukunft freisetzen oder das Alte st\u00e4rken.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Kultureller Widerstand<\/strong><br>Transformationen, ob digital oder nicht, erfordert oft einen tiefgreifenden kulturellen Wandel innerhalb des Unternehmens. Dabei geht es nicht nur darum, neue Technologien zu akzeptieren oder Arbeitsweisen anzupassen. Das ist zu kurz gedacht und zu operativ! Transformationen \u00e4ndern im Wesentlichen die Art und Weise, WIE der Unternehmenszweck erf\u00fcllt wird. Wof\u00fcr werden wir in Zukunft stehen? Welches Verhalten f\u00f6rdert den Erfolg und bringt uns zum Ziel?Wie gehen wir mit alten Routinen um? Die \u201eReflexe\u201c der Mitarbeitenden und F\u00fchrungskr\u00e4fte sind noch ganz und gar in der alten Welt. Das sich durch neues Verhalten eine neue Unternehmenskultur entwickelt, ist ein Marathon, kein Sprint. Es braucht ein allgemeines Bewusstsein zu den gew\u00fcnschten Verhaltensweisen und warum diese f\u00fcr jeden einzelnen vorteilhaft sind. UND es braucht konsequente, soziale Reaktionen bei unerw\u00fcnschtem Verhalten.Gerade unter Druck reagieren wir aus dem Unbewussten heraus, und meist auf der Grundlage alter Erfolgsmuster. Kulturver\u00e4nderung ist deshalb ein intensiver und anstrengender Prozess, mit vielen konstruktiven Feedback- und Korrekturschleifen f\u00fcr alle Beteiligten.<\/li>\n<!-- \/wp:list-item -->\n\n<!-- wp:list-item {\"fontSize\":\"medium\"} -->\n<li class=\"has-medium-font-size\"><strong>Unzureichende Einbindung<\/strong><br>Die Einbindung der Mitarbeiter ist ein entscheidender Erfolgsfaktor f\u00fcr Transformationen. Wenn die Mitarbeiter nicht aktiv in den Transformationsprozess einbezogen werden, ihre Perspektiven nicht geh\u00f6rt werden, kann dies zu Frustration und mangelnder Akzeptanz f\u00fchren. Warum auch sollte es anders sein? Menschen sind keine Lemminge! Und Menschen sind ungern das Opfer von Entscheidungen anderer. Den Prozess, sich mit Neuerungen auseinanderzusetzen, sich eine Meinung zu bilden und den eigenen Weg darin zu suchen, k\u00f6nnen wir nicht abk\u00fcrzen. Wir verlieren nur Zeit, wenn wir die Mitarbeitenden erst zur Implementierung hin einbinden. Durch diesen Zeitverlust riskieren wir den Misserfolg unserer Transformation!<\/li>\n<!-- \/wp:list-item --><\/ul>\n<!-- \/wp:list -->\n\n<!-- wp:image {\"id\":250200,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/1-8.png\" alt=\"\" class=\"wp-image-250200\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Schlechte Transformations-Programme schaden dem Unternehmen<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Wir konnten in den letzten Jahren beobachten, wie ein Change Programm das n\u00e4chste abl\u00f6ste, noch bevor das erste \u00fcberhaupt Ergebnisse hervorbringen konnte. Und was haben wir dadurch erreicht? Richtig - Frust bei der Belegschaft. Die t\u00e4gliche Arbeit wurde mit zus\u00e4tzlichem Aufwand belastet - ohne echte, daraus resultierende Erleichterungen und ohne, dass das versprochene Ergebnis eintrat, denn wir kamen ja gar nicht am Ende an, am versprochenen Zukuntsszenario. Was bleibt ist Ern\u00fcchterung, ein angekratztes Vertrauen in die F\u00fchrungsmannschaft und sinkendes Engagement f\u00fcr die Firmenziele allgemein. \u201eLass mich man nur meinen Job machen und mein Gehalt nach Hause bringen, mehr will ich nicht - mehr mache ich h\u00f6chsten noch privat!\u201c Genauso f\u00fchlt und h\u00f6rt sich ein Misserfolg in der Transformation an.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:image {\"id\":250201,\"sizeSlug\":\"full\",\"linkDestination\":\"none\"} -->\n<figure class=\"wp-block-image size-full\"><img src=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/2-11-e1685443940815.png\" alt=\"Wegweiser: Habits und Changes\" class=\"wp-image-250201\"\/><\/figure>\n<!-- \/wp:image -->\n\n<!-- wp:heading -->\n<h2 class=\"wp-block-heading\">Unternehmen brauchen dringend mehr Ver\u00e4nderungskompetenz<\/h2>\n<!-- \/wp:heading -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Aus den Ursachen des Misserfolg von Transformationen zu lernen, ist ein erster Schritt. Doch das wird nicht reichen, um in Zukunft besser und schneller z will. Was wir in allen Branchen brauchen, ist eine neue Einstellung zur Ver\u00e4nderung!<br>Zu jeder erfolgreichen Transformation gibt es eine Change Management Strategie, die durch Kommunikation, Beteiligung und Umsetzungsbegleitung die Akzeptanz der angestrebten Ver\u00e4nderungen sicherstellt. Und diese Strategie braucht es auf Unternehmensebene ab der ersten Stunde der Transformation. Es braucht Change Enthusiasten, die neugierig sind, Fragen stellen, M\u00f6glichkeiten ausloten - ohne dabei den Wert des bisher Erreichten zu schm\u00e4lern. Wir brauchen Menschen, die Aufbruchstimmung erzeugen k\u00f6nnen, Zuversicht verstr\u00f6men und andere zum \u201eNeu Denken\u201c ermutigen. Und wir brauchen eine deutlich erh\u00f6hte Ver\u00e4nderungskompetenz auf allen F\u00fchrungsebenen, um genau diese Stimulatoren der Ver\u00e4nderung zu unterst\u00fctzen und auf ein abgestimmtes Ziel hin auszurichten. Unternehmen der Zukunft, die sich schnell anpassen k\u00f6nnen, sind lernorientiert. Sie schaffen eine Kultur der Weiterentwicklung, in der Mitarbeiter ihr Wissen erweitern, aus Fehlern lernen, neue F\u00e4higkeiten entwickeln und Best Practices teilen. Dies zusammen mit der Bef\u00e4higung und Erlaubnis, eigene Entscheidungen treffen zu d\u00fcrfen, macht Unternehmen schneller und besser anpassungsf\u00e4hig.<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\">Damit Du herausfinden kannst, wie hoch die Erfolgsaussichten f\u00fcr die Transformation in Deinem Unternehmen sind, habe ich Dir diesen kurzen Fragebogen zusammengestellt. Damit kannst Du \u00fcberpr\u00fcfen, ob es bei euch Schwachstellen gibt, die einen Misserfolg der Transformation wahrscheinlich machen!<\/p>\n<!-- \/wp:paragraph -->\n\n<!-- wp:paragraph {\"fontSize\":\"medium\"} -->\n<p class=\"has-medium-font-size\"><a href=\"https:\/\/coaching-your-change.com\/schwachstellen-finder-fuer-transformationen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hier geht's zum Schwachstellen-Finder!<\/a> Brauchst Du es auf Englisch? Dann klicke <a href=\"https:\/\/coaching-your-change.com\/vulnerability-finder-for-transformations\/\">hier<\/a>!<br><\/p>\n<!-- \/wp:paragraph -->","_et_gb_content_width":"","_themeisle_gutenberg_block_has_review":false,"footnotes":""},"categories":[24],"tags":[],"class_list":["post-250196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-kategorisiert-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6 Ursachen f\u00fcr den Misserfolg von Transformationen<\/title>\n<meta name=\"description\" content=\"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/coaching-your-change.com\/en_gb\/ursachen-misserfolg-transformationen\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6 Ursachen f\u00fcr den Misserfolg von Transformationen\" \/>\n<meta property=\"og:description\" content=\"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/coaching-your-change.com\/en_gb\/ursachen-misserfolg-transformationen\/\" \/>\n<meta property=\"og:site_name\" content=\"coaching-your-change.com\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Kathrin-Schrepfer\/100085420214170\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/people\/Kathrin-Schrepfer\/100085420214170\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-30T10:57:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T07:14:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Kathrin Schrepfer\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kathrin Schrepfer\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/\"},\"author\":{\"name\":\"Kathrin Schrepfer\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#\\\/schema\\\/person\\\/a883cb7c2b5b5302f27eb2ae2ac966b0\"},\"headline\":\"6 Ursachen f\u00fcr den Misserfolg von Transformationen\",\"datePublished\":\"2023-05-30T10:57:20+00:00\",\"dateModified\":\"2023-10-11T07:14:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/\"},\"wordCount\":1462,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#\\\/schema\\\/person\\\/a883cb7c2b5b5302f27eb2ae2ac966b0\"},\"image\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/blogbilder-mai.png\",\"articleSection\":[\"Nicht kategorisiert\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/\",\"url\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/\",\"name\":\"6 Ursachen f\u00fcr den Misserfolg von Transformationen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/blogbilder-mai.png\",\"datePublished\":\"2023-05-30T10:57:20+00:00\",\"dateModified\":\"2023-10-11T07:14:58+00:00\",\"description\":\"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/blogbilder-mai.png\",\"contentUrl\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/blogbilder-mai.png\",\"width\":800,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/ursachen-misserfolg-transformationen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/coaching-your-change.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"6 Ursachen f\u00fcr den Misserfolg von Transformationen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#website\",\"url\":\"https:\\\/\\\/coaching-your-change.com\\\/\",\"name\":\"coaching-your-change.com\",\"description\":\"Change Expertise &amp; Business Coaching\",\"publisher\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#\\\/schema\\\/person\\\/a883cb7c2b5b5302f27eb2ae2ac966b0\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/coaching-your-change.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/#\\\/schema\\\/person\\\/a883cb7c2b5b5302f27eb2ae2ac966b0\",\"name\":\"Kathrin Schrepfer\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/Logo-weiss-short.png\",\"url\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/Logo-weiss-short.png\",\"contentUrl\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/Logo-weiss-short.png\",\"width\":750,\"height\":750,\"caption\":\"Kathrin Schrepfer\"},\"logo\":{\"@id\":\"https:\\\/\\\/coaching-your-change.com\\\/wp-content\\\/uploads\\\/Logo-weiss-short.png\"},\"sameAs\":[\"http:\\\/\\\/coaching-your-change.com\",\"https:\\\/\\\/www.facebook.com\\\/people\\\/Kathrin-Schrepfer\\\/100085420214170\\\/\",\"https:\\\/\\\/www.instagram.com\\\/coaching.your.change\\\/\",\"http:\\\/\\\/linkedin.com\\\/in\\\/kathrin-schrepfer-b041bb19b\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6 Reasons for the failure of transformations","description":"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/coaching-your-change.com\/en_gb\/ursachen-misserfolg-transformationen\/","og_locale":"en_GB","og_type":"article","og_title":"6 Ursachen f\u00fcr den Misserfolg von Transformationen","og_description":"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.","og_url":"https:\/\/coaching-your-change.com\/en_gb\/ursachen-misserfolg-transformationen\/","og_site_name":"coaching-your-change.com","article_publisher":"https:\/\/www.facebook.com\/people\/Kathrin-Schrepfer\/100085420214170\/","article_author":"https:\/\/www.facebook.com\/people\/Kathrin-Schrepfer\/100085420214170\/","article_published_time":"2023-05-30T10:57:20+00:00","article_modified_time":"2023-10-11T07:14:58+00:00","og_image":[{"width":800,"height":550,"url":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png","type":"image\/png"}],"author":"Kathrin Schrepfer","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Kathrin Schrepfer","Estimated reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#article","isPartOf":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/"},"author":{"name":"Kathrin Schrepfer","@id":"https:\/\/coaching-your-change.com\/#\/schema\/person\/a883cb7c2b5b5302f27eb2ae2ac966b0"},"headline":"6 Ursachen f\u00fcr den Misserfolg von Transformationen","datePublished":"2023-05-30T10:57:20+00:00","dateModified":"2023-10-11T07:14:58+00:00","mainEntityOfPage":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/"},"wordCount":1462,"commentCount":0,"publisher":{"@id":"https:\/\/coaching-your-change.com\/#\/schema\/person\/a883cb7c2b5b5302f27eb2ae2ac966b0"},"image":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#primaryimage"},"thumbnailUrl":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png","articleSection":["Nicht kategorisiert"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/","url":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/","name":"6 Reasons for the failure of transformations","isPartOf":{"@id":"https:\/\/coaching-your-change.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#primaryimage"},"image":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#primaryimage"},"thumbnailUrl":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png","datePublished":"2023-05-30T10:57:20+00:00","dateModified":"2023-10-11T07:14:58+00:00","description":"Schlechte Change-Projekte schaden dem Unternehmen. Wer die 6 Ursachen f\u00fcr den Misserfolg von Transformationen kennt, kann vorsorgen.","breadcrumb":{"@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#primaryimage","url":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png","contentUrl":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/blogbilder-mai.png","width":800,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/coaching-your-change.com\/ursachen-misserfolg-transformationen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/coaching-your-change.com\/"},{"@type":"ListItem","position":2,"name":"6 Ursachen f\u00fcr den Misserfolg von Transformationen"}]},{"@type":"WebSite","@id":"https:\/\/coaching-your-change.com\/#website","url":"https:\/\/coaching-your-change.com\/","name":"coaching-your-change.com","description":"Change Expertise &amp; Business Coaching","publisher":{"@id":"https:\/\/coaching-your-change.com\/#\/schema\/person\/a883cb7c2b5b5302f27eb2ae2ac966b0"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/coaching-your-change.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":["Person","Organization"],"@id":"https:\/\/coaching-your-change.com\/#\/schema\/person\/a883cb7c2b5b5302f27eb2ae2ac966b0","name":"Kathrin Schrepfer","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/Logo-weiss-short.png","url":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/Logo-weiss-short.png","contentUrl":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/Logo-weiss-short.png","width":750,"height":750,"caption":"Kathrin Schrepfer"},"logo":{"@id":"https:\/\/coaching-your-change.com\/wp-content\/uploads\/Logo-weiss-short.png"},"sameAs":["http:\/\/coaching-your-change.com","https:\/\/www.facebook.com\/people\/Kathrin-Schrepfer\/100085420214170\/","https:\/\/www.instagram.com\/coaching.your.change\/","http:\/\/linkedin.com\/in\/kathrin-schrepfer-b041bb19b"]}]}},"_links":{"self":[{"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/posts\/250196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/comments?post=250196"}],"version-history":[{"count":9,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/posts\/250196\/revisions"}],"predecessor-version":[{"id":250751,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/posts\/250196\/revisions\/250751"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/media\/250215"}],"wp:attachment":[{"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/media?parent=250196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/categories?post=250196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/coaching-your-change.com\/en_gb\/wp-json\/wp\/v2\/tags?post=250196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}